{"id":70,"count":1,"description":"","link":"https:\/\/docuply.io\/en\/tag\/master-file-en\/","name":"master file","slug":"master-file-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>master file Archive | Docuply<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/docuply.io\/en\/tag\/master-file-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"master file Archive | Docuply\" \/>\n<meta property=\"og:url\" content=\"https:\/\/docuply.io\/en\/tag\/master-file-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Docuply\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@docuplyio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/tag\\\/master-file-en\\\/\",\"url\":\"https:\\\/\\\/docuply.io\\\/en\\\/tag\\\/master-file-en\\\/\",\"name\":\"master file Archive | Docuply\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/tag\\\/master-file-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/tag\\\/master-file-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/docuply.io\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"master file\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/docuply.io\\\/en\\\/\",\"name\":\"Docuply\",\"description\":\"Das elektronische Qualit\u00e4ts\u00admanagement\u00adsystem f\u00fcr Pharma-\u00adKMU und Biotech Start-Ups\",\"publisher\":{\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/docuply.io\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/#organization\",\"name\":\"Docuply\",\"url\":\"https:\\\/\\\/docuply.io\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/docuply.io\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Docuply-Logo-1.0.svg\",\"contentUrl\":\"https:\\\/\\\/docuply.io\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Docuply-Logo-1.0.svg\",\"width\":2913,\"height\":719,\"caption\":\"Docuply\"},\"image\":{\"@id\":\"https:\\\/\\\/docuply.io\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/docuplyio\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/docuply\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"master file Archive | Docuply","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/docuply.io\/en\/tag\/master-file-en\/","og_locale":"en_US","og_type":"article","og_title":"master file Archive | Docuply","og_url":"https:\/\/docuply.io\/en\/tag\/master-file-en\/","og_site_name":"Docuply","twitter_card":"summary_large_image","twitter_site":"@docuplyio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/docuply.io\/en\/tag\/master-file-en\/","url":"https:\/\/docuply.io\/en\/tag\/master-file-en\/","name":"master file Archive | Docuply","isPartOf":{"@id":"https:\/\/docuply.io\/en\/#website"},"breadcrumb":{"@id":"https:\/\/docuply.io\/en\/tag\/master-file-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/docuply.io\/en\/tag\/master-file-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/docuply.io\/en\/"},{"@type":"ListItem","position":2,"name":"master file"}]},{"@type":"WebSite","@id":"https:\/\/docuply.io\/en\/#website","url":"https:\/\/docuply.io\/en\/","name":"Docuply","description":"Das elektronische Qualit\u00e4ts\u00admanagement\u00adsystem f\u00fcr Pharma-\u00adKMU und Biotech Start-Ups","publisher":{"@id":"https:\/\/docuply.io\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/docuply.io\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/docuply.io\/en\/#organization","name":"Docuply","url":"https:\/\/docuply.io\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/docuply.io\/en\/#\/schema\/logo\/image\/","url":"https:\/\/docuply.io\/wp-content\/uploads\/2021\/12\/Docuply-Logo-1.0.svg","contentUrl":"https:\/\/docuply.io\/wp-content\/uploads\/2021\/12\/Docuply-Logo-1.0.svg","width":2913,"height":719,"caption":"Docuply"},"image":{"@id":"https:\/\/docuply.io\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/docuplyio","https:\/\/www.linkedin.com\/company\/docuply\/"]}]}},"_links":{"self":[{"href":"https:\/\/docuply.io\/en\/wp-json\/wp\/v2\/tags\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/docuply.io\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/docuply.io\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/docuply.io\/en\/wp-json\/wp\/v2\/posts?tags=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}